{"id":1122,"count":1,"description":"","link":"https:\/\/ennuestroparche.com\/index.php\/tag\/hambre-cero\/","name":"hambre cero","slug":"hambre-cero","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags\/1122"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts?tags=1122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}