{"id":726,"date":"2023-05-03T17:28:20","date_gmt":"2023-05-03T17:28:20","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=726"},"modified":"2023-05-03T17:52:59","modified_gmt":"2023-05-03T17:52:59","slug":"aprovecha-descuentos-en-predial-2023-para-contribuyentes-de-cali-hasta-junio","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/05\/03\/aprovecha-descuentos-en-predial-2023-para-contribuyentes-de-cali-hasta-junio\/","title":{"rendered":"\u00a1Aprovecha! Descuentos en Predial 2023 para contribuyentes de Cali hasta junio"},"content":{"rendered":"\n<p>Esta medida beneficia a los contribuyentes de la ciudad, quienes ahora tienen m\u00e1s tiempo para realizar su pago y obtener los beneficios correspondientes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"952\" height=\"465\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-122233.png\" alt=\"\" class=\"wp-image-727\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-122233.png 952w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-122233-300x147.png 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-122233-768x375.png 768w\" sizes=\"(max-width: 952px) 100vw, 952px\" \/><figcaption class=\"wp-element-caption\">Imagen tomada de la Alcald\u00eda de Cali<\/figcaption><\/figure><\/div>\n\n\n<p>El plazo para pagar el Impuesto Predial Unificado (IPU) en Santiago de Cali y obtener descuentos se ha ampliado hasta el 30 de junio del a\u00f1o actual, seg\u00fan la decisi\u00f3n tomada por el Departamento Administrativo de Hacienda.<\/p>\n\n\n\n<p>La Resoluci\u00f3n No 4131.010.21.0313 de 2023 ha establecido los nuevos plazos para el pago del impuesto predial, como medida implementada para otorgar facilidades a los contribuyentes. Estos plazos indican cu\u00e1ndo debe ser realizado la cancelaci\u00f3n de este tributo.<\/p>\n\n\n\n<p>Diego Fernando L\u00f3pez Cardona, subdirector de Impuestos y Rentas, resalt\u00f3 que la medida implementada busca principalmente simplificar el proceso de pago para todos los contribuyentes de la ciudad, sin importar si se encuentran al d\u00eda o en situaci\u00f3n de mora. Esto significa que la ampliaci\u00f3n de plazo para pagar el impuesto predial beneficiar\u00e1 a todos por igual.<\/p>\n\n\n\n<p>\u201cTeniendo en cuenta las solicitudes de la ciudadan\u00eda y que en junio muchos contribuyentes reciben prima de mitad de a\u00f1o, se ha tomado la decisi\u00f3n, no solamente de ampliar el plazo para toda la ciudad hasta el 30 de junio con el 15% de descuento, sino tambi\u00e9n otorgar un 10% de descuento a todas aquellas personas que adeuden otras vigencias y cancelen el total de la vigencia 2023\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"752\" height=\"596\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-115228.png\" alt=\"\" class=\"wp-image-728\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-115228.png 752w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-03-115228-300x238.png 300w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><figcaption class=\"wp-element-caption\">Cuadro tomado de la Alcald\u00eda de Cali<\/figcaption><\/figure><\/div>\n\n\n<p>Es relevante mencionar que solo aquellos que paguen el impuesto predial en una sola cuota ser\u00e1n beneficiados con el descuento correspondiente, lo cual significa que los contribuyentes que decidan hacer acuerdos de pago o cancelar en dos o m\u00e1s cuotas no podr\u00e1n obtener este beneficio.<\/p>\n\n\n\n<p>Asimismo, los deudores morosos no necesitan pagar las vigencias anteriores para tener derecho al descuento del 10%, ya que solo requieren hacer el pago correspondiente a la vigencia 2023 para acceder a dicho beneficio.<\/p>\n\n\n\n<p>Esta medida se implementa con el prop\u00f3sito de garantizar la equidad en el cumplimiento de las obligaciones tributarias de todos los contribuyentes y para brindar tranquilidad a la ciudadan\u00eda, al permitirles realizar su pago a tiempo. El Departamento Administrativo de Hacienda ha anunciado que esta es la \u00faltima pr\u00f3rroga que se conceder\u00e1 a los contribuyentes para regularizar su situaci\u00f3n con el Impuesto Predial Unificado. En este sentido, hace un llamado a todos los contribuyentes para que realicen su pago antes de la fecha establecida y puedan acceder a los beneficios fiscales actuales, evitando as\u00ed posibles sanciones por mora.<\/p>\n\n\n\n<p>Asimismo, se recuerda que es posible hacer el pago mediante los canales virtuales habilitados en la p\u00e1gina web de la Alcald\u00eda (<a href=\"http:\/\/www.cali.gov.co\/\">www.cali.gov.co<\/a>) o a trav\u00e9s de la aplicaci\u00f3n Impuestos Cali, con el fin de agilizar el proceso y evitar aglomeraciones en las entidades financieras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta medida beneficia a los contribuyentes de la ciudad, quienes ahora tienen m\u00e1s tiempo para&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[7],"tags":[25,46,161,19],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/726"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":2,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"predecessor-version":[{"id":730,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/726\/revisions\/730"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}