{"id":60,"date":"2023-01-29T02:45:56","date_gmt":"2023-01-29T02:45:56","guid":{"rendered":"https:\/\/np2023test-tech.preview-domain.com\/?p=60"},"modified":"2023-01-29T02:45:56","modified_gmt":"2023-01-29T02:45:56","slug":"espectaculo-cosmico-4-eclipses-este-ano-aqui-te-decimos-como-verlos","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/01\/29\/espectaculo-cosmico-4-eclipses-este-ano-aqui-te-decimos-como-verlos\/","title":{"rendered":"\u00a1Espect\u00e1culo c\u00f3smico! 4 eclipses este a\u00f1o: \u00a1aqu\u00ed te decimos c\u00f3mo verlos!"},"content":{"rendered":"\n<h2>Iniciamos un nuevo a\u00f1o y junto con eso se trae los cuatro eclipses lunares que podr\u00e1n verse desde los diferentes continentes.<\/h2>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/eclipse1.jpg\" alt=\"\" width=\"802\" height=\"529\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/?fbclid=IwAR2D5XihHuGbMN9tXsxEt7SFvS4lbGMBKABkyEIP5vsbKzIpczebPfMJLk8\"><\/a><\/p>\n\n\n\n<p>Estos fen\u00f3menos tendr\u00e1n un efecto visual diferente que empezar\u00e1 en el mes de abril y tendr\u00e1 fin en octubre.<\/p>\n\n\n\n<p>Los eclipses ser\u00e1n: eclipse lunar de sol, penumbral de luna, anular de sol y luna parcial.<\/p>\n\n\n\n<p>Estas anomal\u00edas no pasan con frecuencia, suceden solamente en d\u00edas de luna nueva y luna llena. Estos eclipses lunares suceden cuando la luna queda detr\u00e1s de la tierra y es ah\u00ed, cuando ocurre un eclipse lunar.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/eclipse%203.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/?fbclid=IwAR2D5XihHuGbMN9tXsxEt7SFvS4lbGMBKABkyEIP5vsbKzIpczebPfMJLk8\"><\/a><\/p>\n\n\n\n<h3><strong>\u00bfqu\u00e9 d\u00edas se podr\u00e1 ver los eclipses?<\/strong><\/h3>\n\n\n\n<p>El primer eclipse del a\u00f1o 2023 ocurrir\u00e1 en abril entre los d\u00edas 20 y 21, \u00e9ste ser\u00e1 un fen\u00f3meno totalmente solar, lo podr\u00e1n ver los habitantes del sur de Asia y Australia, en los oc\u00e9anos Pac\u00edfico, \u00cdndico y en la Ant\u00e1rtida.<\/p>\n\n\n\n<p>El segundo eclipse es en el mes de mayo y pasar\u00e1 en la primera semana, entre el d\u00eda 5 y 6, ser\u00e1 penumbral de luna, se podr\u00e1 observar en Europa, Asia, Australia, \u00c1frica. En los oc\u00e9anos Atl\u00e1ntico, Pac\u00edfico e \u00cdndico y en la Ant\u00e1rtida.<\/p>\n\n\n\n<p>El 14 de octubre suceder\u00e1 el eclipse anular de sol. Este fen\u00f3meno se podr\u00e1 presenciar en Suram\u00e9rica, Norteam\u00e9rica, en los oc\u00e9anos del Pac\u00edfico, Atl\u00e1ntico y el \u00c1rtico, adem\u00e1s en el oeste de \u00c1frica.<\/p>\n\n\n\n<p>Por \u00faltimo, el cuarto eclipse que ser\u00e1 lunar parcial ocurrir\u00e1 el 28 y 29 de octubre, podr\u00e1 ser observado por las personas que habitan Suram\u00e9rica, Norteam\u00e9rica, Europa, Asia, \u00c1frica, Australia y en la Ant\u00e1rtida. Tambi\u00e9n se lograr\u00e1 ver en los oc\u00e9anos del Atl\u00e1ntico, Pac\u00edfico, \u00cdndico y \u00c1rtico.<\/p>\n\n\n\n<p>Con esta iniciativa, se espera propiciar espacios de pedagog\u00eda y participaci\u00f3n entre la comunidad, empezando en los colegios hasta las zonas residenciales con altas expectativas de rescatar valores esenciales para vivir mejor y fortalecer los v\u00ednculos de la convivencia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/Collage%20Ruido%20NP.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/?fbclid=IwAR2D5XihHuGbMN9tXsxEt7SFvS4lbGMBKABkyEIP5vsbKzIpczebPfMJLk8\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ennuestroparche.com\/Parche%20Ambiental\/notepierdaslos4eclipsesdela%C3%B1o\/Foto%203%20Campa%C3%B1a.png\" alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Iniciamos un nuevo a\u00f1o y junto con eso se trae los cuatro eclipses lunares que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[5],"tags":[10,11,12],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/60"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":0,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/60\/revisions"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=60"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=60"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}