{"id":257,"date":"2023-02-18T20:51:19","date_gmt":"2023-02-18T20:51:19","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=257"},"modified":"2023-02-18T20:51:20","modified_gmt":"2023-02-18T20:51:20","slug":"enterate-de-las-rutas-del-mio-en-cali-que-dejaran-de-funcionar-a-partir-de-hoy","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/02\/18\/enterate-de-las-rutas-del-mio-en-cali-que-dejaran-de-funcionar-a-partir-de-hoy\/","title":{"rendered":"Ent\u00e9rate de las rutas del MIO en Cali que dejar\u00e1n de funcionar a partir de hoy."},"content":{"rendered":"\n<p>Las modificaciones se deben a la implementaci\u00f3n del reci\u00e9n lanzado plan de servicios del sistema.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n-1024x1024.jpg\" alt=\"\" class=\"wp-image-258\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n-1024x1024.jpg 1024w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n-300x300.jpg 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n-150x150.jpg 150w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n-768x768.jpg 768w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/330174719_704956847998198_5825754022005604219_n.jpg 1058w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagen sacada de: MetrocaliMIO<\/figcaption><\/figure><\/div>\n\n\n<p>A partir de hoy, s\u00e1bado 18 de febrero, en Cali entra en vigencia un nuevo plan de operaci\u00f3n de servicios del MIO, lo que significa que las rutas T37, A23B y A41C ya no estar\u00e1n disponibles para los usuarios.<\/p>\n\n\n\n<p>Teniendo en cuenta lo anterior, aquellas personas que necesiten transportarse en la ciudad deber\u00e1n utilizar otras opciones del sistema de transporte p\u00fablico en la capital del Valle del Cauca.<\/p>\n\n\n\n<p>Los usuarios que actualmente utilizan la ruta T37, que llega hasta la estaci\u00f3n Capri, podr\u00e1n desplazarse utilizando la ruta T31 desde la Terminal Paso del Comercio hasta la estaci\u00f3n Universidades. Durante las horas pico, la frecuencia de la ruta T31 mejorar\u00e1 a 3,25 minutos, lo que garantizar\u00e1 una mejor atenci\u00f3n a los usuarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"464\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/Mural-biopacifico-Estacion-chiminangos-5-06-2-1024x464.jpg\" alt=\"\" class=\"wp-image-259\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/Mural-biopacifico-Estacion-chiminangos-5-06-2-1024x464.jpg 1024w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/Mural-biopacifico-Estacion-chiminangos-5-06-2-300x136.jpg 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/Mural-biopacifico-Estacion-chiminangos-5-06-2-768x348.jpg 768w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/02\/Mural-biopacifico-Estacion-chiminangos-5-06-2.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagen sacada de Metrocali. https:\/\/www.metrocali.gov.co\/<\/figcaption><\/figure>\n\n\n\n<p>Es importante destacar que la ruta T37 se fusionar\u00e1 con la T31 para mejorar su oferta, lo que implicar\u00e1 la incorporaci\u00f3n de m\u00e1s veh\u00edculos para optimizar el servicio y aumentar su frecuencia.<br>Por otra parte, los usuarios de la ruta alimentadora A23B deber\u00e1n usar la ruta A23, la cual contar\u00e1 con un bus complementario dual durante todo el d\u00eda, de lunes a domingo. Esta decisi\u00f3n se tom\u00f3 en coordinaci\u00f3n con los representantes de la comunidad del barrio Los \u00c1lamos, debido a la disminuci\u00f3n de la demanda de la ruta.<\/p>\n\n\n\n<p>Con la inauguraci\u00f3n de la Terminal Aguablanca, se realizar\u00e1n ajustes en el trazado de las rutas A41A, A47, T52 (T42), A44A, C502 y C520, con el fin de integrarlas en las terminales Andr\u00e9s San\u00edn y Aguablanca. De esta forma, se ofrecer\u00e1 a los usuarios de las comunas 14 y 21 una nueva opci\u00f3n de viaje, y por ende, se cancelar\u00e1 el servicio de la ruta A41C.<\/p>\n\n\n\n<p>Para obtener m\u00e1s informaci\u00f3n, los usuarios pueden consultar a los asesores de servicio al cliente, presentes en las distintas estaciones y terminales del sistema, llamar a la l\u00ednea de atenci\u00f3n 6204040 o acceder al canal InfoMIO 3113086000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las modificaciones se deben a la implementaci\u00f3n del reci\u00e9n lanzado plan de servicios del sistema&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[2,8],"tags":[25,46,19,21,49],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/257"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":2,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/257\/revisions"}],"predecessor-version":[{"id":266,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/257\/revisions\/266"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}