{"id":1907,"date":"2024-04-03T16:39:51","date_gmt":"2024-04-03T16:39:51","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=1907"},"modified":"2024-04-05T18:06:49","modified_gmt":"2024-04-05T18:06:49","slug":"hojaldrarte-el-sueno-que-cobro-vida-en-cali-durante-la-pandemia","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2024\/04\/03\/hojaldrarte-el-sueno-que-cobro-vida-en-cali-durante-la-pandemia\/","title":{"rendered":"Hojaldrarte: el sue\u00f1o que cobr\u00f3 vida en Cali durante la pandemia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"475\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE-1024x475.png\" alt=\"\" class=\"wp-image-1908\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE-1024x475.png 1024w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE-300x139.png 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE-768x356.png 768w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE-1536x713.png 1536w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2024\/04\/HOJALDRARTE.png 1810w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: NUESTRO PARCHE<\/figcaption><\/figure>\n\n\n\n<p>Sum\u00e9rgete en la emocionante historia de Mar\u00eda Celmira Quintero, una emprendedora de 63 a\u00f1os cuyo negocio, Hojaldrarte, ha conquistado el coraz\u00f3n del Valle del Cauca. En medio de la pandemia, Mar\u00eda Celmira convirti\u00f3 su pasi\u00f3n por la cocina en un exitoso emprendimiento, con el apoyo invaluable de Servicio Nacional de Aprendizaje SENA, WWB Yaru y otras organizaciones locales. Desde su barrio en Calima hasta los eventos m\u00e1s importantes de la regi\u00f3n, los deliciosos pasteles de Hojaldre Vivo son los protagonistas. A trav\u00e9s de plataformas de venta virtual, Mar\u00eda Celmira ha llevado el sabor y la resiliencia a cada rinc\u00f3n de la comunidad, demostrando que el camino del emprendimiento est\u00e1 lleno de oportunidades para quienes se atreven a perseguir sus sue\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hojaldrarte: el sue\u00f1o que cobr\u00f3 vida en Cali durante la pandemia\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/uQGUEVs7TGA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sum\u00e9rgete en la emocionante historia de Mar\u00eda Celmira Quintero, una emprendedora de 63 a\u00f1os cuyo&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[6,4],"tags":[940,25,46,941,66,814,942,65],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1907"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=1907"}],"version-history":[{"count":2,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1907\/revisions"}],"predecessor-version":[{"id":1911,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1907\/revisions\/1911"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=1907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=1907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=1907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}