{"id":1669,"date":"2023-10-18T04:23:22","date_gmt":"2023-10-18T04:23:22","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=1669"},"modified":"2023-10-18T04:31:54","modified_gmt":"2023-10-18T04:31:54","slug":"preocupacion-crece-estaciones-del-troncal-oriente-del-mio-sufren-actos-de-vandalismo","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/10\/18\/preocupacion-crece-estaciones-del-troncal-oriente-del-mio-sufren-actos-de-vandalismo\/","title":{"rendered":"<strong>Preocupaci\u00f3n crece: estaciones del troncal oriente del M\u00cdO sufren actos de vandalismo<\/strong>"},"content":{"rendered":"\n<p>Hace apenas tres semanas, la tan esperada Troncal Oriente del M\u00cdO comenz\u00f3 su operaci\u00f3n en Cali. Sin embargo, la alegr\u00eda inicial de la comunidad se ha visto empa\u00f1ada por una creciente preocupaci\u00f3n debido a la inseguridad y actos de vandalismo que est\u00e1n afectando la nueva infraestructura.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/10\/thpub_700X400_165301.jpg\" alt=\"\" class=\"wp-image-1670\" width=\"842\" height=\"381\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/10\/thpub_700X400_165301.jpg 700w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/10\/thpub_700X400_165301-300x136.jpg 300w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><figcaption class=\"wp-element-caption\">Troncal del Oriente de Cali<\/figcaption><\/figure>\n\n\n\n<p>Este tramo, que cubre una distancia de 4,2 kil\u00f3metros de los 13 totales que compondr\u00e1n la Troncal, incluye estaciones clave como El Diamante, Antonio Nari\u00f1o, Ciudad Modelo, Rep\u00fablica de Israel, Villa del Sur, Mariano Ramos, Ca\u00f1averales y Sim\u00f3n Bol\u00edvar. Sorprendentemente, en menos de 20 d\u00edas desde su apertura, dos de estas estaciones ya han sufrido da\u00f1os significativos.<\/p>\n\n\n\n<p>Uno de los incidentes tuvo lugar en la estaci\u00f3n de Antonio Nari\u00f1o, donde se informa que un acto de vandalismo provoc\u00f3 da\u00f1os en una de las puertas del vag\u00f3n, dej\u00e1ndola inoperable. Asimismo, en la estaci\u00f3n de Ciudad Modelo, varias barandas que separan el carril exclusivo de los dem\u00e1s carriles de tr\u00e1fico se encuentran dobladas.<\/p>\n\n\n\n<p>La comunidad local, que esperaba una mejora en la seguridad debido a un convenio con la Polic\u00eda, se muestra descontenta. Ricardo Salazar, representante de los usuarios del M\u00cdO, expres\u00f3 su preocupaci\u00f3n: \u00abPr\u00e1cticamente, estas estaciones apenas tienen dos semanas de funcionamiento, y ya vemos da\u00f1os. En esta nueva troncal, las estaciones se encuentran solas, sin seguridad\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"110\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2-1024x110.jpg\" alt=\"\" class=\"wp-image-1598\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2-1024x110.jpg 1024w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2-300x32.jpg 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2-768x83.jpg 768w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2-1536x166.jpg 1536w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/09\/Nuestro-parche-1900x205-2.jpg 1900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.youtube.com\/watch?v=EUWDLjK66to&amp;list=PL7GkGvfBVmFyK-Gea9mDQA8hyw3IJiout\" title=\"\">https:\/\/www.youtube.com\/watch?v=EUWDLjK66to&amp;list=PL7GkGvfBVmFyK-Gea9mDQA8hyw3IJiout<\/a><\/figcaption><\/figure>\n\n\n\n<p>La falta de cultura ciudadana y la inseguridad parecen ser factores clave en estos problemas. Algunos usuarios informan que los tubos que separan el carril exclusivo de las dem\u00e1s v\u00edas no se est\u00e1n desprendiendo, sino que est\u00e1n siendo doblados en un intento de robo. Adem\u00e1s, se han observado casos de vandalismo, como la sustracci\u00f3n de partes de la estaci\u00f3n de Antonio Nari\u00f1o.<\/p>\n\n\n\n<p>Los usuarios est\u00e1n preocupados por la r\u00e1pida aparici\u00f3n de da\u00f1os e irregularidades en las nuevas estaciones, que son esenciales para la movilidad en la zona. Mauricio Sierra, habitante de la zona, critica la falta de compromiso: \u00abEvidencian la falta de compromiso que tiene tanto la ciudadan\u00eda, Metrocali y la Polic\u00eda con el servicio\u00bb.<\/p>\n\n\n\n<p>Adem\u00e1s de la seguridad, los usuarios han identificado otros problemas, como la falta de personal en las taquillas de las estaciones y deficiencias en las m\u00e1quinas de recarga. Algunos ciclistas se quejan de la falta de seguridad para sus bicicletas en los biciparqueaderos.<\/p>\n\n\n\n<p>Tambi\u00e9n se ha se\u00f1alado que la estructura de las estaciones no permite una movilidad libre entre los vagones, lo que dificulta la elecci\u00f3n de rutas. La falta de conexi\u00f3n entre los vagones ha generado preocupaci\u00f3n entre los pasajeros.<\/p>\n\n\n\n<p>La seguridad, o la falta de ella, se ha convertido en una preocupaci\u00f3n constante, especialmente durante las noches, cuando las estaciones se vuelven solitarias y son frecuentadas por personas en situaci\u00f3n de calle y consumidores de drogas.<\/p>\n\n\n\n<p>El diario El Pa\u00eds busc\u00f3 respuestas de Metrocali, pero la entidad deriv\u00f3 la responsabilidad de los da\u00f1os y la seguridad a la Polic\u00eda y la Secretar\u00eda de Seguridad de Cali. Por su parte, la Polic\u00eda de Cali sostiene que, a pesar de su acuerdo de seguridad, Metrocali es la entidad encargada de responder por los da\u00f1os en la infraestructura.<\/p>\n\n\n\n<p>La comunidad espera que se tomen medidas prontas y efectivas para garantizar la seguridad de las estaciones y la satisfacci\u00f3n de los usuarios que confiaron en la Troncal Oriente del M\u00cdO como una soluci\u00f3n de movilidad en la ciudad.<\/p>\n\n\n\n<p>Ver tambien.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tips de Ahorro | Desconecta los aparatos que no est\u00e9s utilizando\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/EUWDLjK66to?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hace apenas tres semanas, la tan esperada Troncal Oriente del M\u00cdO comenz\u00f3 su operaci\u00f3n en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[4],"tags":[719,25,46,435,285,296,716,711,717,715,111,616,718,16,562,720,721,713,162,19,627,712,573,714],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1669"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=1669"}],"version-history":[{"count":1,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1669\/revisions"}],"predecessor-version":[{"id":1671,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1669\/revisions\/1671"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=1669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=1669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=1669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}