{"id":1371,"date":"2023-08-01T19:24:21","date_gmt":"2023-08-01T19:24:21","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=1371"},"modified":"2023-08-02T20:16:03","modified_gmt":"2023-08-02T20:16:03","slug":"exitoso-foro-de-importacion-de-alimentos-busca-reducir-la-dependencia-en-el-valle-del-cauca","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/08\/01\/exitoso-foro-de-importacion-de-alimentos-busca-reducir-la-dependencia-en-el-valle-del-cauca\/","title":{"rendered":"<strong>Exitoso Foro de Importaci\u00f3n de Alimentos busca reducir la dependencia en el Valle del Cauca<\/strong>"},"content":{"rendered":"\n<p><em>El pasado 27 de julio a las 2:00 pm, se llev\u00f3 a cabo con gran \u00e9xito el Foro de Importaci\u00f3n de Alimentos en el Auditorio Cementos Argos de la Universidad ICESI, reuniendo a destacados representantes del Ministerio de Agricultura, FENALCE, FENALCO, DAATER, CIAT, as\u00ed como a profesionales de la industria y empresarios del sector alimentario. El objetivo principal fue explorar las tendencias y desaf\u00edos relacionados con la importaci\u00f3n de alimentos y estudiar diferentes estrategias para reducir la dependencia de las importaciones en el Valle del Cauca.<\/em><\/p>\n\n\n\n<p>El evento cont\u00f3 con la participaci\u00f3n de destacados actores del sector, incluyendo representantes del Ministerio de Agricultura, FENALCE, FENALCO, DAATER, CIAT, as\u00ed como profesionales de la industria y empresarios del sector alimentario.<\/p>\n\n\n\n<p>Durante el foro, se presentaron diversas ponencias y se abordaron temas cruciales relacionados con la importaci\u00f3n de alimentos, entre ellos, el remplazo de importaciones agropecuarias, la inflaci\u00f3n que alcanz\u00f3 un 9.37 % en los \u00faltimos 6 meses seg\u00fan datos de CAVASA, cifra por encima del promedio nacional del 7.34%, y su impacto en la seguridad alimentaria.<\/p>\n\n\n\n<p>El Dr. Carlos Arturo Alom\u00eda D\u00edaz, Gerente de CAVSA, comparti\u00f3 su perspectiva sobre la importancia del evento: \u00abDurante los \u00faltimos seis meses, hemos comercializado 180,000 toneladas de alimentos procedentes de diferentes regiones del pa\u00eds y del mundo, lo que evidencia la relevancia de la din\u00e1mica comercial. Estamos buscando crear inter\u00e9s en un tema que hemos detectado en nuestro quehacer diario: la comercializaci\u00f3n para beneficiar a los consumidores vallecaucanos.\u00bb<\/p>\n\n\n\n<p>A su vez, el Dr. Alom\u00eda agreg\u00f3: \u00abEl prop\u00f3sito fundamental de este tercer foro tiene que ver con reducir la importaci\u00f3n de alimentos que consumen los cuatro y medio millones de vallecaucanos. Tenemos dos cordilleras, un valle plano geogr\u00e1fico y toda la capacidad tecnol\u00f3gica y profesional para desarrollar alternativas que nos permitan disminuir nuestra dependencia de las importaciones.\u00bb<\/p>\n\n\n\n<p>El foro tambi\u00e9n abord\u00f3 la preocupaci\u00f3n sobre el costo de la canasta familiar, el cual se ha mantenido alto debido a factores como el impacto del invierno en el aumento de precios. Adem\u00e1s, se discuti\u00f3 el impacto de eventos internacionales, como la Guerra de Ucrania, en la econom\u00eda global y el comportamiento del d\u00f3lar, que afecta directamente la estabilizaci\u00f3n de precios en el mercado de alimentos.<\/p>\n\n\n\n<p>En resumen, el Foro de Importaci\u00f3n de Alimentos result\u00f3 ser una plataforma valiosa para explorar estrategias y soluciones que permitan reducir la dependencia de lo que se puede producir en el Valle del Cauca y promover la seguridad alimentaria en la regi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"3\u00b0 foro Cavasa: La importaci\u00f3n de alimentos en la seguridad alimentaria - Nuestro Parche\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/be0Yg2sexr4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 27 de julio a las 2:00 pm, se llev\u00f3 a cabo con gran&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1371"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=1371"}],"version-history":[{"count":2,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1371\/revisions"}],"predecessor-version":[{"id":1377,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1371\/revisions\/1377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media\/1372"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=1371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=1371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=1371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}