{"id":1311,"date":"2023-07-24T15:18:39","date_gmt":"2023-07-24T15:18:39","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=1311"},"modified":"2023-07-26T16:12:36","modified_gmt":"2023-07-26T16:12:36","slug":"ultimas-noticias-jorge-ivan-ospina-enfrenta-cargos-en-su-mandato-como-alcalde-de-cali","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/07\/24\/ultimas-noticias-jorge-ivan-ospina-enfrenta-cargos-en-su-mandato-como-alcalde-de-cali\/","title":{"rendered":"\u00daltimas Noticias: Jorge Iv\u00e1n Ospina Enfrenta Cargos en su Mandato como Alcalde de Cali"},"content":{"rendered":"\n<p>El d\u00eda de inicio de la semana, la Procuradur\u00eda tom\u00f3 al alcalde por sorpresa al presentarle un documento que contiene acusaciones en su contra debido a supuestas anomal\u00edas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"792\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/07\/Alcalde-de-Cli-1024x792.png\" alt=\"\" class=\"wp-image-1321\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/07\/Alcalde-de-Cli-1024x792.png 1024w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/07\/Alcalde-de-Cli-300x232.png 300w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/07\/Alcalde-de-Cli-768x594.png 768w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/07\/Alcalde-de-Cli.png 1077w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagen tomada de Twitter | <a href=\"https:\/\/twitter.com\/edrucali\">@edrucali<\/a><\/figcaption><\/figure>\n\n\n\n<p>La Procuradur\u00eda General de la Naci\u00f3n ha puesto su atenci\u00f3n en el alcalde de Cali, Jorge Iv\u00e1n Ospina G\u00f3mez, debido a presuntas irregularidades relacionadas con la Feria de Cali de 2020. Como resultado, se ha emitido un pliego de cargos tanto contra \u00e9l como contra el secretario de Cultura de la ciudad, Jos\u00e9 Darwin Lenis Mej\u00eda. Seg\u00fan la informaci\u00f3n recopilada por la entidad, el convenio entre la ciudad y Corfecali para la organizaci\u00f3n de la feria habr\u00eda sido firmado por una suma de 11.955 millones de pesos sin contar con estudios previos exhaustivos y suficientes que respaldaran ese monto.<\/p>\n\n\n\n<p>Al parecer, durante el a\u00f1o 2020, en plena pandemia, se estableci\u00f3 el convenio bas\u00e1ndose en la indexaci\u00f3n de costos de los tres a\u00f1os previos, sin tener en consideraci\u00f3n que, para ese momento, los eventos se llevar\u00edan a cabo de manera virtual.<\/p>\n\n\n\n<p>Seg\u00fan la Procuradur\u00eda, el Distrito deber\u00eda haber incluido en los estudios previos la metodolog\u00eda utilizada para calcular los precios de los eventos a realizar: \u201ccosa que en este caso no aconteci\u00f3, pues como ha quedado evidenciado, tan s\u00f3lo se hizo referencia a la&nbsp;<strong>informaci\u00f3n hist\u00f3rica bajo presupuestos que no eran aplicables<\/strong>&nbsp;para realizar una&nbsp;<strong>feria virtual<\/strong>\u201d, indic\u00f3 el Ministerio P\u00fablico.<\/p>\n\n\n\n<p>El \u00f3rgano de supervisi\u00f3n indic\u00f3 que el alcalde Ospina podr\u00eda haber descuidado sus responsabilidades de control, vigilancia y supervisi\u00f3n en el proceso de contrataci\u00f3n, el cual estaba a cargo del secretario de Cultura, Lenis Mej\u00eda. Supuestamente, el alcalde no fue advertido sobre los cambios contractuales relacionados con la organizaci\u00f3n de la feria, no solicit\u00f3 ning\u00fan informe sobre la metodolog\u00eda utilizada para establecer los costos, y tampoco pidi\u00f3 explicaciones sobre la inclusi\u00f3n de elementos propios de eventos presenciales.<\/p>\n\n\n\n<p>Debido a estos hechos, la Procuradur\u00eda clasific\u00f3 la conducta del alcalde Ospina G\u00f3mez como una falta grave, cometida con culpa grav\u00edsima, mientras que la del secretario Lenis Mej\u00eda fue catalogada tambi\u00e9n con culpa grav\u00edsima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda de inicio de la semana, la Procuradur\u00eda tom\u00f3 al alcalde por sorpresa al&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[7],"tags":[399,397,25,398,387],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1311"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":3,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"predecessor-version":[{"id":1335,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1311\/revisions\/1335"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}