{"id":1101,"date":"2023-06-28T23:44:58","date_gmt":"2023-06-28T23:44:58","guid":{"rendered":"https:\/\/ennuestroparche.com\/?p=1101"},"modified":"2023-06-28T23:44:58","modified_gmt":"2023-06-28T23:44:58","slug":"feria-de-cali-en-riesgo-financiero-se-cancelara-la-esperada-edicion-2023","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/06\/28\/feria-de-cali-en-riesgo-financiero-se-cancelara-la-esperada-edicion-2023\/","title":{"rendered":"Feria de Cali en riesgo financiero: \u00bfSe cancelar\u00e1 la esperada edici\u00f3n 2023?"},"content":{"rendered":"\n<p>Los informes emitidos por la Contralor\u00eda y la Revisor\u00eda Fiscal podr\u00edan revelar esta situaci\u00f3n, seg\u00fan han expresado los concejales, quienes solicitan la liquidaci\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"547\" height=\"383\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria-2.jpg\" alt=\"\" class=\"wp-image-1102\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria-2.jpg 547w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria-2-300x210.jpg 300w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/figure><\/div>\n\n\n<p>A menos de seis meses de la celebraci\u00f3n de la Feria de Cali, se han dado a conocer dos informes que exponen la complicada situaci\u00f3n financiera de Corfecali, seg\u00fan revelan el Revisor Fiscal de la entidad y la Contralor\u00eda de Cali, documentos a los que El Pa\u00eds tuvo acceso.<\/p>\n\n\n\n<p>El informe del Revisor Fiscal de Corfecali, fechado el 30 de mayo, y el informe preliminar de la Contralor\u00eda, fechado el 9 de junio de este a\u00f1o y que cuenta con un letrero de fondo que indica su naturaleza, han sido verificados por miembros de la junta Directiva de la entidad para confirmar su veracidad. Estos informes plantean una situaci\u00f3n financiera dif\u00edcil que podr\u00eda poner en riesgo la celebraci\u00f3n de la festividad m\u00e1s importante de los cale\u00f1os.<\/p>\n\n\n\n<p>\u201cAmbos informes son reales&#8230; la cosa est\u00e1 muy compleja (en Corfecali) por el tema financiero, por p\u00e9rdidas, p\u00e9rdidas de patrimonio, no hay caja todo eso&#8230;\u201d, dijo un miembro de la Junta Directiva de Corfecali.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"576\" height=\"333\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria.jpg\" alt=\"\" class=\"wp-image-1103\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria.jpg 576w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/Feria-300x173.jpg 300w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/div>\n\n\n<p>De acuerdo con el informe del Revisor Fiscal, Corfecali ten\u00eda cuentas por cobrar al Municipio de Cali por un total de $4.424 millones correspondientes a la Feria 2021. Sin embargo, se registr\u00f3 un deterioro de $800 millones en esas cuentas. Adem\u00e1s, se se\u00f1ala que Corfecali tuvo p\u00e9rdidas en el ejercicio hasta el 31 de diciembre de 2022, alcanzando un valor de $3.926 millones. Como resultado, su patrimonio neto a esa fecha era de $447 millones.<\/p>\n\n\n\n<p>\u201cA lo anterior debe agregarse la falta de liquidez de la entidad, lo cual no ha permitido atender el oportuno pago de sus obligaciones con proveedores, acreedores, empleados y obligaciones tributarias, situaci\u00f3n que pone en riesgo la situaci\u00f3n de Corfecali lo que representa una incertidumbre en materia sobre la capacidad de la entidad para continuar como empresa en marcha\u201d, reza el documento.<\/p>\n\n\n\n<p>A fecha de abril de 2023, la Corporaci\u00f3n segu\u00eda registrando una p\u00e9rdida contable de $2.218 millones, lo que resultaba en un patrimonio neto negativo de $1.770 millones. Hasta el momento, no se han reportado ingresos relevantes que permitan cubrir los gastos fijos de la operaci\u00f3n.<\/p>\n\n\n\n<p>La Contralor\u00eda de Cali ha identificado varias observaciones relacionadas con Corfecali, incluyendo 19 con implicaciones disciplinarias, 3 con implicaciones penales y 5 con implicaciones fiscales, por un monto total de $624.317.398.<\/p>\n\n\n\n<p>Entre las irregularidades de \u00edndole penal y disciplinaria, se destaca la ausencia de actas de reuniones de la Junta Directiva de Corfecali, donde se habr\u00edan otorgado autorizaciones al Gerente para la celebraci\u00f3n de convenios interadministrativos relacionados con Prefer\u00eda, por un valor de $3.450.700.000, y de la Feria, por un valor de $14.854.818.546, los cuales fueron suscritos entre la Secretar\u00eda de Cultura y Corfecali. Estos contratos excedieron los l\u00edmites de autorizaci\u00f3n del representante legal de Corfecali, sin contar con una autorizaci\u00f3n expresa y espec\u00edfica de la Junta Directiva.<\/p>\n\n\n\n<p>Es importante mencionar que debido a estas acciones, entre otras, el anterior Gerente de Corfecali fue destituido de su cargo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"567\" height=\"411\" src=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/feria-3.jpg\" alt=\"\" class=\"wp-image-1104\" srcset=\"https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/feria-3.jpg 567w, https:\/\/ennuestroparche.com\/wp-content\/uploads\/2023\/06\/feria-3-300x217.jpg 300w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><\/figure><\/div>\n\n\n<p>La Contralor\u00eda determin\u00f3 que el contrato de gesti\u00f3n contractual relacionado con los convenios interadministrativos de pre feria y feria present\u00f3 deficiencias significativas, ya que se identificaron vulneraciones a los principios de planeaci\u00f3n. Se sospecha que existieron sobrecostos y que hubo debilidades en el seguimiento y control por parte de la supervisi\u00f3n. En consecuencia, se considera que la gesti\u00f3n realizada fue ineficiente.<\/p>\n\n\n\n<p>\u201cQueda evidenciado que hay una p\u00e9rdida del capital de Corfecali de cerca de $2200 millones, un detrimento en su patrimonio, hay p\u00e9rdidas de esas magnitud lo cual significa que est\u00e1 en crisis y que seguramente hay que pensar en su liquidaci\u00f3n y crear un nuevo esquema que organice la Feria de Cali, porque estos problemas se vienen presentando a\u00f1o tras a\u00f1o y se necesitan soluciones de fondo\u201d, concluy\u00f3 el concejal Terry Hurtado.<\/p>\n\n\n\n<p>En vista de esta situaci\u00f3n complicada, artistas tanto de Cali como de diversas regiones del pa\u00eds han expresado su denuncia sobre el hecho de que a\u00fan no se les ha realizado el pago por sus servicios prestados durante su participaci\u00f3n en la Feria de Cali.<\/p>\n\n\n\n<p>\u201cSomos ocho bandas que fuimos desde Bucaramanga, que participamos en la Feria de Cali y hasta el momento no nos han pagado los honorarios. Nosotros tuvimos una reuni\u00f3n el pasado 5 de mayo con Argemiro Cort\u00e9s y \u00e9l hizo un compromiso de pago para el 30 de mayo. Lleg\u00f3 la fecha y tampoco se logr\u00f3 al acuerdo\u201d manifest\u00f3 Carolina Delgado, directora de la Banda Enkel\u00e9.<\/p>\n\n\n\n<p>Varios artistas de Cali se encuentran en la misma situaci\u00f3n, ya que est\u00e1n a la espera de recibir sus pagos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los informes emitidos por la Contralor\u00eda y la Revisor\u00eda Fiscal podr\u00edan revelar esta situaci\u00f3n, seg\u00fan&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[2,7],"tags":[26,25,46,78,337,19,49],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1101"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=1101"}],"version-history":[{"count":1,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1101\/revisions"}],"predecessor-version":[{"id":1105,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/1101\/revisions\/1105"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=1101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=1101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=1101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}