{"id":103,"date":"2023-01-28T22:47:08","date_gmt":"2023-01-28T22:47:08","guid":{"rendered":"http:\/\/np2023test.tech\/?p=1"},"modified":"2023-01-28T22:47:08","modified_gmt":"2023-01-28T22:47:08","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/ennuestroparche.com\/index.php\/2023\/01\/28\/hello-world\/","title":{"rendered":"Los Cale\u00f1os est\u00e1n HARTOS de los peligrosos piques ilegales!"},"content":{"rendered":"\n<h4>En Cali, barrio Prados del Sur comuna 18, los Piques, el stunt ilegal y el presunto consumo de estupefacientes son una pr\u00e1ctica que se viene presentando en la Avenida Circunvalar a la altura de la carrera 70.<\/h4>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ennuestroparche.com\/Social\/Ciudadanos%20cansados%20de%20los%20Piques%20y%20el%20Stunt%20ilegal\/WhatsApp%20Image%202023-01-23%20at%2012.53.07%20PM.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/ennuestroparche.com\/Social\/Ciudadanos%20cansados%20de%20los%20Piques%20y%20el%20Stunt%20ilegal\/?fbclid=IwAR2UyYOIvvmYQHnUj-wuRcoCHeJdH8AYlJUeIVdNAuU1qwFykVYrpPFBEpA\"><\/a><\/p>\n\n\n\n<p>Los habitantes de esta zona han presenciado actividad de alto riesgo por esta v\u00eda, donde se construy\u00f3 la ampliaci\u00f3n de la Avenida Circunvalar, calle 1ra con 77 en el barrio Prados del Sur, donde los fines de semana es cuando m\u00e1s se realizan estas actividades y la poblaci\u00f3n habla sobre el riesgo que hay al cruzar la calle, puesto que la v\u00eda peatonal tambi\u00e9n es transitada por las motos, los ni\u00f1os tambi\u00e9n se ven involucrados en este peligro, ya que al lado de esta v\u00eda est\u00e1 la Instituci\u00f3n Educativa Juan Pablo II.<\/p>\n\n\n\n<p>La comunidad cansados de los piques y el stunt ilegal, realizaron su denuncia ante las autoridades competentes y es all\u00ed donde la fuerza p\u00fablica actu\u00f3 ante los estragos que se ven\u00edan presentando.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ennuestroparche.com\/Social\/Ciudadanos%20cansados%20de%20los%20Piques%20y%20el%20Stunt%20ilegal\/piques.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/ennuestroparche.com\/Social\/Ciudadanos%20cansados%20de%20los%20Piques%20y%20el%20Stunt%20ilegal\/?fbclid=IwAR2UyYOIvvmYQHnUj-wuRcoCHeJdH8AYlJUeIVdNAuU1qwFykVYrpPFBEpA\"><\/a><\/p>\n\n\n\n<p>Ya van 3 domingos consecutivos que la Polic\u00eda Nacional, los Antimotines, la Alcald\u00eda y seg\u00fan los habitantes del barrio, mencionan sobre la presencia de bienestar familiar; asisten al lugar para controlar la problem\u00e1tica del stunt y los piques ilegales, donde los guardas de tr\u00e1nsito han incautado cantidades de motos sin los documentos requeridos y presuntamente han rescatado motos que ten\u00edan denuncia por hurto.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Nosenvian?src=hash&amp;ref_src=twsrc%5Etfw\">#Nosenvian<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/actualizado?src=hash&amp;ref_src=twsrc%5Etfw\">#actualizado<\/a> <br>3 domingos consecutivos que la <a href=\"https:\/\/twitter.com\/PoliciaCali?ref_src=twsrc%5Etfw\">@PoliciaCali<\/a>, los Antimotines, la <a href=\"https:\/\/twitter.com\/AlcaldiaDeCali?ref_src=twsrc%5Etfw\">@AlcaldiaDeCali<\/a>  y seg\u00fan los habitantes del barrio, mencionan sobre la presencia de <a href=\"https:\/\/twitter.com\/ICBFColombia?ref_src=twsrc%5Etfw\">@ICBFColombia<\/a>; asisten al lugar para controlar la problem\u00e1tica del stunt y los piques ilegales. <a href=\"https:\/\/t.co\/sGvXRdE8h2\">pic.twitter.com\/sGvXRdE8h2<\/a><\/p>&mdash; Nuestro Parche (@nuestroparcheOF) <a href=\"https:\/\/twitter.com\/nuestroparcheOF\/status\/1617664840390307842?ref_src=twsrc%5Etfw\">January 23, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En Cali, barrio Prados del Sur comuna 18, los Piques, el stunt ilegal y el&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false},"categories":[8],"tags":[19],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/103"}],"collection":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":0,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"wp:attachment":[{"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ennuestroparche.com\/index.php\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}